{"id":1133,"count":1,"description":"","link":"https:\/\/fsportsnet.com\/fr\/tag\/sports-net-design-support\/","name":"assistance \u00e0 la conception de filets de sport","slug":"sports-net-design-support","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/fsportsnet.com\/fr\/wp-json\/wp\/v2\/tags\/1133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fsportsnet.com\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/fsportsnet.com\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/fsportsnet.com\/fr\/wp-json\/wp\/v2\/posts?tags=1133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}